{"id":13255,"date":"2023-07-03T12:47:08","date_gmt":"2023-07-03T10:47:08","guid":{"rendered":"http:\/\/www.reconnectivetherapy.com\/?post_type=tribe_events&#038;p=13255"},"modified":"2023-07-06T16:22:48","modified_gmt":"2023-07-06T14:22:48","slug":"rct-inneres-ueben-nuggets-serie","status":"publish","type":"tribe_events","link":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/","title":{"rendered":"Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen!"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Ein Angebot, um dich durch diese beispiellosen Zeiten zu f\u00fchren und zu unterst\u00fctzen.<\/p>\n<p><strong>Nugget `Erwachen zu neuen Nervenbahnen!\u00b4<\/strong><br \/>\n<strong><br \/>\n<\/strong>Unsere gegenw\u00e4rtigen Zeiten sind stark gepr\u00e4gt von Ungewissheiten und Unbekanntem. Dies zu durchleben ist f\u00fcr viele eine besonders unangenehme und unbehagliche Situation. Wir verfangen uns leicht in einer Endlosschleife an Gedanken, die \u00c4ngste ausl\u00f6sen, welche wiederum weitere schmerzhafte Gedanken triggern. Diese Schleifen bestehen aus unseren Gedanken, unseren Emotionen und unseren Nervenbahnen.<\/p>\n<p>Die gute Nachricht ist:<br \/>\nWir k\u00f6nnen zu mehr innerer Freiheit gelangen indem wir trainieren NEUE Nervenbahnen anzusteuern.<\/p>\n<p><strong>6 Onlinekonferenzen\u00a0<\/strong>(Teilnahme auch \u00fcber Telefon m\u00f6glich)<\/p>\n<p><strong>Voraussetzung zur Teilnahme:<\/strong>\u00a0keine<\/p>\n<p><strong>NEUE Termine:<\/strong><br \/>\nMontag,\u00a010. April<br \/>\nMontag,\u00a017. April<br \/>\nMontag,\u00a024. April<br \/>\nMontag,\u00a001. Mai<br \/>\nMontag,\u00a008. Mai<br \/>\nMontag,\u00a015. Mai<\/p>\n<p><strong>Zeit:\u00a0<\/strong>20:00 h \u2013 20:45 h<\/p>\n<p><strong>Leitung:\u00a0<\/strong>Kerstin Sch\u00f6n<\/p>\n<p><strong>Kosten: <\/strong>175,- \u20ac<\/p>\n<p><strong>Anmeldeschluss:<\/strong>\u00a009. April 2023, 12:00h MEZ[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/2&#8243;][vc_btn title=&#8220;Mehr Infos&#8220; size=&#8220;lg&#8220; align=&#8220;center&#8220; link=&#8220;url:http%3A%2F%2Fwww.reconnectivetherapy.com%2Fde%2Finneres-ueben%2Fnuggets%2F&#8220;][\/vc_column][vc_column width=&#8220;1\/2&#8243;][vc_btn title=&#8220;Anmeldung&#8220; size=&#8220;lg&#8220; align=&#8220;center&#8220; link=&#8220;url:mailto%3Ainfo.de%40reconnectivetherapy.com%3Fsubject%3DNugget%20-%20Erwache%20zu%20neuen%20Nervenbahnen%20-%206%20Online-Konferenzen%20-%20meine%20Anmeldung%26body%3DHallo%2C%250a%250ahiermit%20melde%20ich%20mich%20f%C3%BCr%20die%20o.%20gen.%20Online-Konferenzen%2C%20beginnend%20am%2010.04.2023%2C%20an.%250a%250aDie%20Kosten%20in%20H%C3%B6he%20von%20%E2%82%AC175%2C-%20habe%20ich%20mit%20entsprechendem%20Vermerk%20auf%20folgendes%20Konto%20%C3%BCberwiesen%3A%20ReConnective%20Therapy%20-%20Kerstin%20Sch%C3%B6n%20IBAN%3A%20DE58%207019%200000%200207%206641%2076%250a%250aIch%20bitte%20um%20Aufnahme%20in%20die%20Telegram-Gruppe%20und%20in%20den%20entsprechenden%20Kanal.%20Meine%20Mobilnummer%3A%250a%250a%250a%250aBeste%20Gr%C3%BC%C3%9Fe&#8220;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Ein Angebot, um dich durch diese beispiellosen Zeiten zu f\u00fchren und zu unterst\u00fctzen. Nugget `Erwachen zu neuen Nervenbahnen!\u00b4 Unsere gegenw\u00e4rtigen Zeiten sind stark gepr\u00e4gt von Ungewissheiten<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":21,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-13255","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen! - RCT - Reconnective Therapy | Kerstin Sch\u00f6n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen! - RCT - Reconnective Therapy | Kerstin Sch\u00f6n\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Ein Angebot, um dich durch diese beispiellosen Zeiten zu f\u00fchren und zu unterst\u00fctzen. Nugget `Erwachen zu neuen Nervenbahnen!\u00b4 Unsere gegenw\u00e4rtigen Zeiten sind stark gepr\u00e4gt von Ungewissheiten [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/\" \/>\n<meta property=\"og:site_name\" content=\"RCT - Reconnective Therapy | Kerstin Sch\u00f6n\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T14:22:48+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-inneres-ueben-nuggets-serie\\\/\",\"url\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-inneres-ueben-nuggets-serie\\\/\",\"name\":\"Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen! - RCT - Reconnective Therapy | Kerstin Sch\u00f6n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/#website\"},\"datePublished\":\"2023-07-03T10:47:08+00:00\",\"dateModified\":\"2023-07-06T14:22:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-inneres-ueben-nuggets-serie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-inneres-ueben-nuggets-serie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-inneres-ueben-nuggets-serie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/\",\"name\":\"RCT - Reconnective Therapy | Kerstin Sch\u00f6n\",\"description\":\"RCT - Reconnective Therapy | Kerstin Sch\u00f6n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen! - RCT - Reconnective Therapy | Kerstin Sch\u00f6n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/","og_locale":"de_DE","og_type":"article","og_title":"Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen! - RCT - Reconnective Therapy | Kerstin Sch\u00f6n","og_description":"[vc_row][vc_column][vc_column_text]Ein Angebot, um dich durch diese beispiellosen Zeiten zu f\u00fchren und zu unterst\u00fctzen. Nugget `Erwachen zu neuen Nervenbahnen!\u00b4 Unsere gegenw\u00e4rtigen Zeiten sind stark gepr\u00e4gt von Ungewissheiten [\u2026]","og_url":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/","og_site_name":"RCT - Reconnective Therapy | Kerstin Sch\u00f6n","article_modified_time":"2023-07-06T14:22:48+00:00","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/","url":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/","name":"Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen! - RCT - Reconnective Therapy | Kerstin Sch\u00f6n","isPartOf":{"@id":"https:\/\/www.reconnectivetherapy.com\/#website"},"datePublished":"2023-07-03T10:47:08+00:00","dateModified":"2023-07-06T14:22:48+00:00","breadcrumb":{"@id":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-inneres-ueben-nuggets-serie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.reconnectivetherapy.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.reconnectivetherapy.com\/events\/"},{"@type":"ListItem","position":3,"name":"Inneres \u00dcben \u2013 Nugget Serie: Erwachen zu neuen Nervenbahnen!"}]},{"@type":"WebSite","@id":"https:\/\/www.reconnectivetherapy.com\/#website","url":"https:\/\/www.reconnectivetherapy.com\/","name":"RCT - Reconnective Therapy | Kerstin Sch\u00f6n","description":"RCT - Reconnective Therapy | Kerstin Sch\u00f6n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reconnectivetherapy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tribe_events\/13255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/users\/21"}],"version-history":[{"count":0,"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tribe_events\/13255\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/media?parent=13255"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tags?post=13255"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=13255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}