{"id":13198,"date":"2023-07-03T10:47:21","date_gmt":"2023-07-03T08:47:21","guid":{"rendered":"http:\/\/www.reconnectivetherapy.com\/?post_type=tribe_events&#038;p=13198"},"modified":"2023-07-03T10:47:59","modified_gmt":"2023-07-03T08:47:59","slug":"rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system","status":"publish","type":"tribe_events","link":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/","title":{"rendered":"RCT-BehandlerIn  \u2013  Weiterbildung APE-Spezial \u201cLymphatisches System\u201d"},"content":{"rendered":"<p>Obwohl uns ein neues Energiesystem zur Verf\u00fcgung steht, ist es bei den meisten von uns noch nicht vollst\u00e4ndig in den K\u00f6rperzellen verankert. In dieser \u00dcbergangsphase leistet das lymphatische System zus\u00e4tzliche Arbeit.<br \/>\nIn der ReConnective Therapy habe ich immer wieder gesehen, wie effizient sich die Informationen aus dem neuen Energiesystem mit den Schichten des Energiek\u00f6rpers verbinden k\u00f6nnen, die dem physischen K\u00f6rper am n\u00e4chsten sind und diese neuen Informationen dann in den physischen Zellen verankern. Dies hat sich als sehr effizient erwiesen.<br \/>\nDiese Ausbildung aktiviert sowohl dein physisches als auch dein energetisches Lymphsystem und unterst\u00fctzt dein Wachstum und deine F\u00e4higkeit als RCT-Therapeut.<\/p>\n<p><strong>Voraussetzung zur Teilnahme: <\/strong>Abschluss des Kurses APE 1<\/p>\n<p><strong>Termin:<em>\u00a0<\/em><\/strong>Samstag, 21. Januar \u2013 Sonntag, 22. Januar<\/p>\n<p><strong>Zeit: <\/strong>tgl.\u00a010:00h bis 18:00h<\/p>\n<p><strong>Ort:<\/strong> Praxis Dirkorte, Obermarkt 6, D \u2013 82418 Murnau<\/p>\n<p><strong>Online:<\/strong> via ZOOM-Konferenz<\/p>\n<p><strong>Leitung: <\/strong>Kerstin Sch\u00f6n<\/p>\n<p><strong>Kursgeb\u00fchr:<\/strong>\u00a0600,- \u20ac<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obwohl uns ein neues Energiesystem zur Verf\u00fcgung steht, ist es bei den meisten von uns noch nicht vollst\u00e4ndig in den K\u00f6rperzellen verankert. In dieser \u00dcbergangsphase leistet<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":21,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-13198","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RCT-BehandlerIn \u2013 Weiterbildung APE-Spezial \u201cLymphatisches System\u201d - RCT - Reconnective Therapy | Kerstin Sch\u00f6n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RCT-BehandlerIn \u2013 Weiterbildung APE-Spezial \u201cLymphatisches System\u201d - RCT - Reconnective Therapy | Kerstin Sch\u00f6n\" \/>\n<meta property=\"og:description\" content=\"Obwohl uns ein neues Energiesystem zur Verf\u00fcgung steht, ist es bei den meisten von uns noch nicht vollst\u00e4ndig in den K\u00f6rperzellen verankert. In dieser \u00dcbergangsphase leistet [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/\" \/>\n<meta property=\"og:site_name\" content=\"RCT - Reconnective Therapy | Kerstin Sch\u00f6n\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-03T08:47:59+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\\\/\",\"url\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\\\/\",\"name\":\"RCT-BehandlerIn \u2013 Weiterbildung APE-Spezial \u201cLymphatisches System\u201d - RCT - Reconnective Therapy | Kerstin Sch\u00f6n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/#website\"},\"datePublished\":\"2023-07-03T08:47:21+00:00\",\"dateModified\":\"2023-07-03T08:47:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/de\\\/event\\\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RCT-BehandlerIn \u2013 Weiterbildung APE-Spezial \u201cLymphatisches System\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/\",\"name\":\"RCT - Reconnective Therapy | Kerstin Sch\u00f6n\",\"description\":\"RCT - Reconnective Therapy | Kerstin Sch\u00f6n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reconnectivetherapy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RCT-BehandlerIn \u2013 Weiterbildung APE-Spezial \u201cLymphatisches System\u201d - RCT - Reconnective Therapy | Kerstin Sch\u00f6n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/","og_locale":"de_DE","og_type":"article","og_title":"RCT-BehandlerIn \u2013 Weiterbildung APE-Spezial \u201cLymphatisches System\u201d - RCT - Reconnective Therapy | Kerstin Sch\u00f6n","og_description":"Obwohl uns ein neues Energiesystem zur Verf\u00fcgung steht, ist es bei den meisten von uns noch nicht vollst\u00e4ndig in den K\u00f6rperzellen verankert. In dieser \u00dcbergangsphase leistet [\u2026]","og_url":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/","og_site_name":"RCT - Reconnective Therapy | Kerstin Sch\u00f6n","article_modified_time":"2023-07-03T08:47:59+00:00","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/","url":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/","name":"RCT-BehandlerIn \u2013 Weiterbildung APE-Spezial \u201cLymphatisches System\u201d - RCT - Reconnective Therapy | Kerstin Sch\u00f6n","isPartOf":{"@id":"https:\/\/www.reconnectivetherapy.com\/#website"},"datePublished":"2023-07-03T08:47:21+00:00","dateModified":"2023-07-03T08:47:59+00:00","breadcrumb":{"@id":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.reconnectivetherapy.com\/de\/event\/rct-behandlerin-weiterbildung-ape-spezial-lymphatisches-system\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.reconnectivetherapy.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.reconnectivetherapy.com\/events\/"},{"@type":"ListItem","position":3,"name":"RCT-BehandlerIn \u2013 Weiterbildung APE-Spezial \u201cLymphatisches System\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.reconnectivetherapy.com\/#website","url":"https:\/\/www.reconnectivetherapy.com\/","name":"RCT - Reconnective Therapy | Kerstin Sch\u00f6n","description":"RCT - Reconnective Therapy | Kerstin Sch\u00f6n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reconnectivetherapy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tribe_events\/13198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/users\/21"}],"version-history":[{"count":0,"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tribe_events\/13198\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/media?parent=13198"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tags?post=13198"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.reconnectivetherapy.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=13198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}